{"id":3537,"date":"2022-02-22T12:42:29","date_gmt":"2022-02-22T11:42:29","guid":{"rendered":"https:\/\/www.lesmerveillesdupacifique.com\/?post_type=product&#038;p=3537"},"modified":"2026-04-01T15:23:53","modified_gmt":"2026-04-01T13:23:53","slug":"boucles-argent-avec-perles-ovales-boa18","status":"publish","type":"product","link":"https:\/\/www.lesmerveillesdupacifique.com\/en\/produit\/boucles-argent-avec-perles-ovales-boa18\/","title":{"rendered":"Silver earrings with oval pearls &#8211; BOA18"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>2 Tahitian cultured pearls<\/strong><br \/>\n<strong>shape:<\/strong> oval<br \/>\n<strong>diameter:<\/strong>\u00a08-9 mm<br \/>\n<strong>quality:<\/strong> A\/B<br \/>\n<strong>925 rhodium silver &#8211;<\/strong>\u00a01 gram<\/p>\n","protected":false},"featured_media":4150,"template":"","meta":{"_mi_skip_tracking":false},"product_cat":[18],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesmerveillesdupacifique.com\/en\/produit\/boucles-argent-avec-perles-ovales-boa18\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique\" \/>\n<meta property=\"og:description\" content=\"2 Tahitian cultured pearls shape: oval diameter:\u00a08-9 mm quality: A\/B 925 rhodium silver -\u00a01 gram\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Merveilles du Pacifique\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T13:23:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/fr\/#website\",\"url\":\"https:\/\/www.lesmerveillesdupacifique.com\/fr\/\",\"name\":\"Les Merveilles du Pacifique\",\"description\":\"Perles de culture de Tahiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lesmerveillesdupacifique.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg\",\"contentUrl\":\"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg\",\"width\":2000,\"height\":1334,\"caption\":\"www.photographe-book-paris.com\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#webpage\",\"url\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/\",\"name\":\"Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#primaryimage\"},\"datePublished\":\"2022-02-22T11:42:29+00:00\",\"dateModified\":\"2026-04-01T13:23:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lesmerveillesdupacifique.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\/\/www.lesmerveillesdupacifique.com\/fr\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Boucles d&rsquo;oreilles argent avec perles ovales &#8211; BOA18\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesmerveillesdupacifique.com\/en\/produit\/boucles-argent-avec-perles-ovales-boa18\/","og_locale":"en_US","og_type":"article","og_title":"Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique","og_description":"2 Tahitian cultured pearls shape: oval diameter:\u00a08-9 mm quality: A\/B 925 rhodium silver -\u00a01 gram","og_url":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/","og_site_name":"Les Merveilles du Pacifique","article_modified_time":"2026-04-01T13:23:53+00:00","og_image":[{"width":2000,"height":1334,"url":"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.lesmerveillesdupacifique.com\/fr\/#website","url":"https:\/\/www.lesmerveillesdupacifique.com\/fr\/","name":"Les Merveilles du Pacifique","description":"Perles de culture de Tahiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesmerveillesdupacifique.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg","contentUrl":"https:\/\/www.lesmerveillesdupacifique.com\/wp-content\/uploads\/2022\/02\/BOA18.jpg","width":2000,"height":1334,"caption":"www.photographe-book-paris.com"},{"@type":"WebPage","@id":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#webpage","url":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/","name":"Silver earrings with oval pearls - BOA18 - Les Merveilles du Pacifique","isPartOf":{"@id":"https:\/\/www.lesmerveillesdupacifique.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#primaryimage"},"datePublished":"2022-02-22T11:42:29+00:00","dateModified":"2026-04-01T13:23:53+00:00","breadcrumb":{"@id":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesmerveillesdupacifique.com\/produit\/boucles-argent-avec-perles-ovales-boa18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lesmerveillesdupacifique.com\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/www.lesmerveillesdupacifique.com\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Boucles d&rsquo;oreilles argent avec perles ovales &#8211; BOA18"}]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/product\/3537"}],"collection":[{"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/media\/4150"}],"wp:attachment":[{"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/media?parent=3537"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/product_cat?post=3537"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lesmerveillesdupacifique.com\/en\/wp-json\/wp\/v2\/product_tag?post=3537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}